{"id":26521,"date":"2022-02-09T20:10:08","date_gmt":"2022-02-09T20:10:08","guid":{"rendered":"https:\/\/live-lite-lincdire-project.pantheonsite.io\/?p=26521"},"modified":"2022-02-09T20:12:12","modified_gmt":"2022-02-09T20:12:12","slug":"ma-philosophie-de-lenseignement-5","status":"publish","type":"post","link":"https:\/\/lite.lincdireproject.org\/de\/2022\/02\/ma-philosophie-de-lenseignement-5\/","title":{"rendered":"Ma philosophie de l\u2019enseignement"},"content":{"rendered":"<p>Please register or login to access LITE.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"Ma pratique de l'enseignement est centr\u00e9e sur la stimulation des forces des \u00e9l\u00e8ves et la cr\u00e9ation d'un environnement confortable o\u00f9&nbsp;<a href=\"https:\/\/lite.lincdireproject.org\/de\/2022\/02\/ma-philosophie-de-lenseignement-5\/\">[&hellip;]<\/a>","protected":false},"author":2526,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/posts\/26521"}],"collection":[{"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/users\/2526"}],"replies":[{"embeddable":true,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/comments?post=26521"}],"version-history":[{"count":2,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/posts\/26521\/revisions"}],"predecessor-version":[{"id":26523,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/posts\/26521\/revisions\/26523"}],"wp:attachment":[{"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/media?parent=26521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/categories?post=26521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lite.lincdireproject.org\/de\/wp-json\/wp\/v2\/tags?post=26521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}